{"id":1637,"date":"2022-12-23T11:29:47","date_gmt":"2022-12-23T09:29:47","guid":{"rendered":"https:\/\/www.dgusv.de\/news-blog\/?p=1637"},"modified":"2022-12-12T11:33:00","modified_gmt":"2022-12-12T09:33:00","slug":"wir-wuenschen-allen-frohe-weihnachten-und-einen-guten-rutsch-ins-neue-jahr","status":"publish","type":"post","link":"https:\/\/www.dgusv.de\/news-blog\/wir-wuenschen-allen-frohe-weihnachten-und-einen-guten-rutsch-ins-neue-jahr\/","title":{"rendered":"Wir w\u00fcnschen allen frohe Weihnachten und einen guten Rutsch ins neue Jahr!"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.dgusv.de\/news-blog\/wp-content\/uploads\/Frohe-Weihanchten.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"377\" src=\"https:\/\/www.dgusv.de\/news-blog\/wp-content\/uploads\/Frohe-Weihanchten-1024x377.jpg\" alt=\"\" class=\"wp-image-1638\" srcset=\"https:\/\/www.dgusv.de\/news-blog\/wp-content\/uploads\/Frohe-Weihanchten-1024x377.jpg 1024w, https:\/\/www.dgusv.de\/news-blog\/wp-content\/uploads\/Frohe-Weihanchten-300x110.jpg 300w, https:\/\/www.dgusv.de\/news-blog\/wp-content\/uploads\/Frohe-Weihanchten-768x283.jpg 768w, https:\/\/www.dgusv.de\/news-blog\/wp-content\/uploads\/Frohe-Weihanchten-624x230.jpg 624w, https:\/\/www.dgusv.de\/news-blog\/wp-content\/uploads\/Frohe-Weihanchten.jpg 1250w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">Frohe Weihnachten an die gesamte Gutachter- und Sachverst\u00e4ndigenbranche<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Liebe Mitglieder, liebe Partner, liebe Weggef\u00e4hrten,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">das Jahr 2022 ist in den letzten Z\u00fcgen und f\u00fcr viele hat der Weihnachtsurlaub bereits begonnen. Wir m\u00f6chten diese Gelegenheit nutzen, um noch einmal zur\u00fcckzublicken, \u201eDanke\u201c zu sagen und Ihnen alles Gute zu w\u00fcnschen!<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">Irgendwie hat das vergangene Jahr unsere Gesellschaft ganz sch\u00f6n durchgesch\u00fcttelt. Immerhin j\u00e4hrt sich bald bereits der Beginn des Russland-Ukraine-Krieges. Die Folgen dessen sind dramatisch und konnten nicht vorhergesehen werden: Inflation, steigende Energiekosten, weltweite Lebensmittel- und Ressourcenknappheit. Und ganz vorneweg: das unendliche Leid der ukrainischen Menschen und ihrer Angeh\u00f6rigen. Es gibt kaum Worte, die unser Mitgef\u00fchl passend beschreiben k\u00f6nnten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dar\u00fcber hinaus bleiben nach wie vor die Coronajahre unvergessen. Nach wie vor h\u00e4lt uns der Virus auf Trab. Und ge\u00e4nderte Arbeitsweisen wie beispielsweise Homeoffice und Video-Konferenzen sind mittlerweile zum Standard geworden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bei all den gro\u00dfen und schwerwiegenden Ereignissen wollen wir das Positive nicht vergessen: Der DGuSV steht mit seiner starken Community geschlossen zusammen. Gemeinsam bewirken wir weiterhin viel Gutes f\u00fcr unsere Branche und einzelne Individuen. Wir sind sehr dankbar und freuen uns \u00fcber einen stetig steigenden Zuwachs und m\u00f6chten auch in Zukunft selbstbewusst und kompetent die wichtige Instanz f\u00fcr unsere Mitglieder bleiben, die wir geworden sind.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In diesem Sinne freuen wir uns darauf, n\u00e4chstes Jahr genauso und besser weiterzumachen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bis dahin verabschieden wir uns mit weihnachtlichen Festtagsgr\u00fc\u00dfen. Wir w\u00fcnschen Ihnen und Ihrer Familie alles Gute und einen guten Rutsch. Herzlichen Dank f\u00fcr Ihren Support und Ihr Vertrauen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Weiter geht es im Jahr 2023 mit frischer Energie und viel Hoffnung auf Gutes,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ihr DGuSV-Team!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Liebe Mitglieder, liebe Partner, liebe Weggef\u00e4hrten, das Jahr 2022 ist in den letzten Z\u00fcgen und f\u00fcr viele hat der Weihnachtsurlaub bereits begonnen. Wir m\u00f6chten diese Gelegenheit nutzen, um noch einmal zur\u00fcckzublicken, \u201eDanke\u201c zu sagen und Ihnen alles Gute zu w\u00fcnschen!<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1637","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"_links":{"self":[{"href":"https:\/\/www.dgusv.de\/news-blog\/wp-json\/wp\/v2\/posts\/1637","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dgusv.de\/news-blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dgusv.de\/news-blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dgusv.de\/news-blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dgusv.de\/news-blog\/wp-json\/wp\/v2\/comments?post=1637"}],"version-history":[{"count":1,"href":"https:\/\/www.dgusv.de\/news-blog\/wp-json\/wp\/v2\/posts\/1637\/revisions"}],"predecessor-version":[{"id":1639,"href":"https:\/\/www.dgusv.de\/news-blog\/wp-json\/wp\/v2\/posts\/1637\/revisions\/1639"}],"wp:attachment":[{"href":"https:\/\/www.dgusv.de\/news-blog\/wp-json\/wp\/v2\/media?parent=1637"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dgusv.de\/news-blog\/wp-json\/wp\/v2\/categories?post=1637"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dgusv.de\/news-blog\/wp-json\/wp\/v2\/tags?post=1637"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}