{"id":1258,"date":"2020-03-09T12:44:10","date_gmt":"2020-03-09T10:44:10","guid":{"rendered":"https:\/\/www.dgusv.de\/news-blog\/?p=1258"},"modified":"2020-03-09T12:44:10","modified_gmt":"2020-03-09T10:44:10","slug":"schimmelbildung-in-wohnraeumen-immobiliengutachter-sind-gefragt","status":"publish","type":"post","link":"https:\/\/www.dgusv.de\/news-blog\/schimmelbildung-in-wohnraeumen-immobiliengutachter-sind-gefragt\/","title":{"rendered":"Schimmelbildung in Wohnr\u00e4umen. Immobiliengutachter sind gefragt!"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.dgusv.de\/news-blog\/wp-content\/uploads\/Fotolia_82743446_XL-1024x683.jpg\" alt=\"Immobiliengutachter\" class=\"wp-image-1018\" srcset=\"https:\/\/www.dgusv.de\/news-blog\/wp-content\/uploads\/Fotolia_82743446_XL-1024x683.jpg 1024w, https:\/\/www.dgusv.de\/news-blog\/wp-content\/uploads\/Fotolia_82743446_XL-300x200.jpg 300w, https:\/\/www.dgusv.de\/news-blog\/wp-content\/uploads\/Fotolia_82743446_XL-768x512.jpg 768w, https:\/\/www.dgusv.de\/news-blog\/wp-content\/uploads\/Fotolia_82743446_XL-624x416.jpg 624w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>Immobiliengutachter<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">In der kalten Jahreszeit kommen besonders h\u00e4ufig F\u00e4lle von Schimmelbefall auf. Auch Gutachter aus der Immobilien-Branche k\u00f6nnen damit zu tun haben. Denn in manchen F\u00e4llen k\u00f6nnen neben nutzerbedingtem Verhalten auch bauteilbedingte Umst\u00e4nde damit zusammenh\u00e4ngen. Wir schauen uns das genauer an. <\/p>\n\n\n\n<!--more-->\n\n\n\n<h2 class=\"wp-block-heading\">K\u00e4lte von drau\u00dfen bringt Schummel nach innen<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn es drau\u00dfen kalt wird, nimmt die Temperatur von\nunged\u00e4mmten Au\u00dfenw\u00e4nden und Geschossdecken ab. Daraus folgt wiederum eine\nDurchl\u00e4ssigkeit der W\u00e4nde und Decken \u2013&nbsp;auch die R\u00e4ume erkalten. Was\ngeschieht in diesem Fall? Ganz genau, die Heizung wird aufgedreht. Und das ist\nauch gut so. Nur leider erreicht die W\u00e4rme nicht alle Stellen. Vor allem Ecken\nan W\u00e4nden und \u00dcberg\u00e4nge zu Decke und Boden bleiben kalt. Das sind die\nsogenannten W\u00e4rmebr\u00fccken, an denen Schimmelbildung vor allem zutage tritt. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Luftfeuchtigkeit bietet zus\u00e4tzlichen N\u00e4hrboden<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Umso h\u00f6her die Luftfeuchte in R\u00e4umen ist, desto mehr wird\nSchimmelbildung beg\u00fcnstigt. Besonders ab 80% spricht man von einem erh\u00f6hten\nRisiko. Denn dann wird das Bauteil feucht. Der Schimmelpilz kann sich anlagern\nund sich weiter ausbreiten. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bei 100% relativer Luftfeuchte kondensiert die Luft sogar\nund es bilden sich Tropfen. Die sogenannten Taupunkte sind erreicht. Man kennt\ndieses Ph\u00e4nomen von Fenstern, die auf einmal von innen her nass sind. Oftmals\nist das vor allem nach hei\u00dfem Duschen oder Kochen der Fall. Wird in diesen\nF\u00e4llen nicht ausreichend gel\u00fcftet, k\u00f6nnen auch die kalten W\u00e4nde nass werden. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Generell gilt: Tritt eine konstante Luftfeuchte von 70% auf,\nwird die Schimmelpilzbildung im Innenraum nachhaltig beg\u00fcnstigt, wobei dies\nauch unter Tapeten stattfinden kann und somit nicht unbedingt auf den ersten\nBlick ersichtlich ist. Erst wenn der Schaden durch Schimmelpilz schon vorangeschritten\nist, l\u00e4sst sich der Befall auch optisch erkennen. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Das empfehlen Gutachter aus der Immobilien-Branche ihren\nKunden<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Um einem Befall vorzubeugen, empfiehlt sich eine gute L\u00fcftung\nder R\u00e4umlichkeiten. Mehrmals am Tag Sto\u00dfl\u00fcften und Querl\u00fcften ist am besten, um\neinen effektiven Luftaustausch zu gew\u00e4hrleisten. Parallel dazu sollte man die\nR\u00e4ume dann wieder beheizen, um so eine gute Balance herzustellen. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In einigen R\u00e4umen sollte dar\u00fcber hinaus ein Feuchtigkeitsmesser\naufgestellt sein, der die Luftfeuchte anzeigt. Die Messger\u00e4te sind g\u00fcnstig\nerh\u00e4ltlich und machen sich bew\u00e4hrt. Denn hiernach kann man sich zuverl\u00e4ssig\nrichten und sichergehen, dass man dem Schimmel keine Chance l\u00e4sst. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Luftfeuchte: Welcher Wert ist normal?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Wer einen Luftfeuchtigkeitsmesser\nin den R\u00e4umen hat, der kann genau nachsehen: Ein dauerhafter Wert zwischen 40%\nund 60% ist ideal. Nach dem Duschen beispielsweise kann der Wert auch mal h\u00f6her\nliegen, sollte durch L\u00fcften aber schnell wieder herunterreguliert werden. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Was, wenn\ntrotzdem Schimmelpilz auftaucht?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Nicht immer\nist es ausschlie\u00dflich das Nutzerverhalten, das einen Befall beg\u00fcnstigt. Es k\u00f6nnen\nauch die Umgebungsbedingungen sein, die den Pilzbefall die T\u00fcren \u00f6ffnen. Auch\neine Vorbelastung macht es den Sporen einfacher, sich durch die Luft wieder\nanzusiedeln. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sofern der Befall von Schimmel nicht durch L\u00fcften und Heizen\nbehoben werden kann, liegt unter Umst\u00e4nden ein Baumangel vor. Und sp\u00e4testens\ndann, liebe Kollegen, kommen Sie zum Einsatz. Jetzt ist ein kompetenter\nGutachter gefragt, der die Sache unter die Lupe nimmt. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ob ein baulicher Mangel vorliegt oder die Bewohner den Befall\nmitverursacht haben: Schimmel ist eine unsch\u00f6ne Angelegenheit, die sogar zu\nchronischen Krankheiten f\u00fchren kann. Kein Wunder also, dass sich viele Klienten\nan einen Immobiliengutachter wenden, um hier schon vor Bezug einer Immobilie Bescheid\nzu wissen. Und das aus gutem Grund. Denn es gibt Verk\u00e4ufer und Vermieter, die\nSchimmelbefall vors\u00e4tzlich vertuschen. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sie sind Immobilien-Gutachter und haben Erfahrungen mit\nSchimmelbefall gemacht? Teilen Sie uns mit, was Ihren Arbeitsalltag bewegt. Wir\nsind gespannt,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ihr DGuSV-Team <\/p>\n","protected":false},"excerpt":{"rendered":"<p>In der kalten Jahreszeit kommen besonders h\u00e4ufig F\u00e4lle von Schimmelbefall auf. Auch Gutachter aus der Immobilien-Branche k\u00f6nnen damit zu tun haben. Denn in manchen F\u00e4llen k\u00f6nnen neben nutzerbedingtem Verhalten auch bauteilbedingte Umst\u00e4nde damit zusammenh\u00e4ngen. Wir schauen uns das genauer an.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1258","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"_links":{"self":[{"href":"https:\/\/www.dgusv.de\/news-blog\/wp-json\/wp\/v2\/posts\/1258","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dgusv.de\/news-blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dgusv.de\/news-blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dgusv.de\/news-blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dgusv.de\/news-blog\/wp-json\/wp\/v2\/comments?post=1258"}],"version-history":[{"count":1,"href":"https:\/\/www.dgusv.de\/news-blog\/wp-json\/wp\/v2\/posts\/1258\/revisions"}],"predecessor-version":[{"id":1259,"href":"https:\/\/www.dgusv.de\/news-blog\/wp-json\/wp\/v2\/posts\/1258\/revisions\/1259"}],"wp:attachment":[{"href":"https:\/\/www.dgusv.de\/news-blog\/wp-json\/wp\/v2\/media?parent=1258"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dgusv.de\/news-blog\/wp-json\/wp\/v2\/categories?post=1258"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dgusv.de\/news-blog\/wp-json\/wp\/v2\/tags?post=1258"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}